{"id":34,"count":2,"description":"","link":"https:\/\/bauet.ac.bd\/cse\/category\/research\/","name":"Research","slug":"research","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Research Archives - Department of Computer Science and Engineering<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bauet.ac.bd\/cse\/category\/research\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Research Archives - Department of Computer Science and Engineering\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bauet.ac.bd\/cse\/category\/research\/\" \/>\n<meta property=\"og:site_name\" content=\"Department of Computer Science and Engineering\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/bauet.ac.bd\\\/cse\\\/category\\\/research\\\/\",\"url\":\"https:\\\/\\\/bauet.ac.bd\\\/cse\\\/category\\\/research\\\/\",\"name\":\"Research Archives - Department of Computer Science and Engineering\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bauet.ac.bd\\\/cse\\\/#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bauet.ac.bd\\\/cse\\\/#website\",\"url\":\"https:\\\/\\\/bauet.ac.bd\\\/cse\\\/\",\"name\":\"Department of Computer Science and Engineering\",\"description\":\"Bangladesh Army University of Engineering &amp; Technology\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bauet.ac.bd\\\/cse\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Research Archives - Department of Computer Science and Engineering","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bauet.ac.bd\/cse\/category\/research\/","og_locale":"en_US","og_type":"article","og_title":"Research Archives - Department of Computer Science and Engineering","og_url":"https:\/\/bauet.ac.bd\/cse\/category\/research\/","og_site_name":"Department of Computer Science and Engineering","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/bauet.ac.bd\/cse\/category\/research\/","url":"https:\/\/bauet.ac.bd\/cse\/category\/research\/","name":"Research Archives - Department of Computer Science and Engineering","isPartOf":{"@id":"https:\/\/bauet.ac.bd\/cse\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/bauet.ac.bd\/cse\/#website","url":"https:\/\/bauet.ac.bd\/cse\/","name":"Department of Computer Science and Engineering","description":"Bangladesh Army University of Engineering &amp; Technology","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bauet.ac.bd\/cse\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/bauet.ac.bd\/cse\/wp-json\/wp\/v2\/categories\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bauet.ac.bd\/cse\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/bauet.ac.bd\/cse\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/bauet.ac.bd\/cse\/wp-json\/wp\/v2\/posts?categories=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}